{"id":287,"date":"2023-06-19T09:03:55","date_gmt":"2023-06-19T09:03:55","guid":{"rendered":"https:\/\/wilddrone.ch\/?p=287"},"modified":"2023-09-14T12:58:54","modified_gmt":"2023-09-14T12:58:54","slug":"detection-faune-ia-sncf","status":"publish","type":"post","link":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/","title":{"rendered":"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l&rsquo;IA pour le SNCF R\u00e9seau"},"content":{"rendered":"<h2><a href=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-260\" src=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg\" alt=\"\" width=\"2560\" height=\"641\" srcset=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg 2560w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-300x75.jpg 300w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-1024x257.jpg 1024w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-768x192.jpg 768w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-1536x385.jpg 1536w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-210x53.jpg 210w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-1960x491.jpg 1960w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/a><\/h2>\n<h2>R\u00e9sum\u00e9<\/h2>\n<p>L&rsquo;objectif du projet de recherche, qui est men\u00e9 \u00e0 la FHNW en collaboration avec SNCF R\u00e9seau, est d&rsquo;utiliser l&rsquo;<b>intelligence artificielle <\/b>(IA) et une <b>int\u00e9gration de donn\u00e9es multimodales<\/b> (s\u00e9ries temporelles multispectrales par satellite, images a\u00e9riennes, informations agricoles et climatologiques, ainsi que des donn\u00e9es provenantes de capteurs terrestres) pour <b>mod\u00e9liser les probabilit\u00e9s de r\u00e9sidence de la faune<\/b> \u00e0 proximit\u00e9 de l&rsquo;infrastructure des voies du r\u00e9seau de la SNCF.<\/p>\n<p>Les mod\u00e8les d&rsquo;habitat pr\u00e9dictif qui en r\u00e9sultent aideront \u00e0 mieux <b>pr\u00e9venir les incidents<\/b>, par exemple par des mesures de construction appropri\u00e9es dans des zones \u00e0 risque sp\u00e9cifiques.<\/p>\n<p>Dans ce projet Big Data, les derni\u00e8res technologies de Machine Learning doivent \u00eatre appliqu\u00e9es afin de pouvoir traiter les sources de donn\u00e9es extr\u00eamement exhaustives et exigeantes et d&rsquo;<b>\u00e9tablir des corr\u00e9lations profitables<\/b> \u00e0 partir du traitement.<\/p>\n<p>Le projet est bas\u00e9 sur une exp\u00e9rience reconnue de plusieurs ann\u00e9es de l&rsquo;Institut de g\u00e9omatique de la FHNW dans le domaine des approches bas\u00e9es sur l&rsquo;IA pour la d\u00e9tection, les t\u00e2ches de classification et la mod\u00e9lisation dans le domaine des g\u00e9odonn\u00e9es compl\u00e8tes avec r\u00e9f\u00e9rence spatiale et temporelle.<\/p>\n<p>&nbsp;<\/p>\n<h2>Introduction<\/h2>\n<p>Dans le cadre d&rsquo;une collaboration, les chercheurs <a href=\"https:\/\/www.fhnw.ch\/de\/personen\/adrian-meyer\">Adrian Meyer<\/a> (sp\u00e9cialiste des g\u00e9odonn\u00e9es et biologiste animalier) et <a href=\"https:\/\/www.fhnw.ch\/de\/personen\/denis-jordan\">Denis Jordan<\/a> (professeur de math\u00e9matiques appliqu\u00e9es) ont lanc\u00e9 un projet en 2023 avec Pascal Baran, <a href=\"https:\/\/www.sncf-reseau.com\/fr\">SNCF R\u00e9seau<\/a>, la branche infrastructure de la soci\u00e9t\u00e9 nationale des chemins de fer fran\u00e7ais. L&rsquo;\u00e9quipe exploite la puissance de l&rsquo;apprentissage automatique pour s&rsquo;attaquer \u00e0 un probl\u00e8me croissant sur les voies ferr\u00e9es : Les accidents li\u00e9s \u00e0 la faune et \u00e0 la flore.<\/p>\n<p>Les accidents impliquant des animaux sauvages, en particulier des sangliers et des cerfs, repr\u00e9sentent un risque important pour le vaste r\u00e9seau ferroviaire fran\u00e7ais. Ils posent non seulement des probl\u00e8mes \u00e9cologiques, de s\u00e9curit\u00e9 et de propri\u00e9t\u00e9, mais entra\u00eenent \u00e9galement des co\u00fbts financiers importants, estim\u00e9s jusqu&rsquo;\u00e0 100 000 euros par incident sur les lignes \u00e0 grande vitesse, tout en totalisant plus de 200 000 minutes de retard chaque ann\u00e9e. Les m\u00e9thodes traditionnelles pour \u00e9viter ces accidents, telles que les cl\u00f4tures, les passages pour animaux sauvages et les dispositifs d&rsquo;effarouchement, demandent beaucoup de ressources et ne sont pas toujours efficaces, car il est difficile de pr\u00e9dire les points chauds de la faune.<\/p>\n<p>Cependant, l&rsquo;\u00e9quipe vise \u00e0 r\u00e9volutionner ce processus en cr\u00e9ant un syst\u00e8me complet de pr\u00e9diction des risques d&rsquo;accidents impliquant des animaux sauvages. \u00c0 l&rsquo;aide d&rsquo;une s\u00e9rie de sources de donn\u00e9es, ils d\u00e9veloppent un mod\u00e8le pr\u00e9dictif dynamique qui utilise de nouveaux algorithmes d&rsquo;apprentissage automatique pour \u00e9valuer le risque de pr\u00e9sence d&rsquo;animaux dans des zones sp\u00e9cifiques. Ces informations permettront des interventions plus pr\u00e9cises et plus rentables, ce qui pourrait r\u00e9duire le nombre d&rsquo;accidents et renforcer la fiabilit\u00e9 et la s\u00e9curit\u00e9 du r\u00e9seau.<\/p>\n<p>Les mod\u00e8les int\u00e9greront des images provenant d&rsquo;ensembles de donn\u00e9es de t\u00e9l\u00e9d\u00e9tection a\u00e9rienne et satellitaire, des photographies de cartographie mobile bas\u00e9es sur des pistes et des images infrarouges provenant de drones et de pi\u00e8ges photographiques. Ces donn\u00e9es seront utilis\u00e9es pour former un mod\u00e8le de fusion multimodale pr\u00e9dictif qui g\u00e9n\u00e8re des scores de risque localis\u00e9s, mettant en \u00e9vidence les points chauds potentiels pour la faune et la flore. Une fois convertis en cartes, ces scores de risque constitueront un outil essentiel pour planifier des mesures d&rsquo;att\u00e9nuation.<\/p>\n<p>Ce projet est une r\u00e9ponse \u00e0 la forte augmentation r\u00e9cente des incidents li\u00e9s \u00e0 la faune sur les chemins de fer fran\u00e7ais, qui comprennent environ 30 000 km de lignes. L&rsquo;\u00e9chelle du pays n\u00e9cessite des structures de bases de donn\u00e9es g\u00e9ospatiales modernes utilisant des strat\u00e9gies Big Data efficaces. Avec environ 1 500 incidents de r\u00e9gularit\u00e9 li\u00e9s \u00e0 des rencontres avec des animaux sauvages qui affecteront environ 8 000 trains d&rsquo;ici 2020, la SNCF a reconnu la n\u00e9cessit\u00e9 d&rsquo;une solution innovante.<\/p>\n<p>L&rsquo;objectif final est un prototype de logiciel flexible capable de pr\u00e9dire la pr\u00e9sence d&rsquo;animaux sur de larges portions du r\u00e9seau SNCF. Il calculera un facteur de risque de collision pour des sections \u00e0 petite \u00e9chelle sur chaque voie, fournissant une base d&rsquo;information localis\u00e9e multitemporelle pour des processus tels que la construction de barri\u00e8res, la mise en \u0153uvre de passages pour animaux, ou des interventions telles que des dispositifs d&rsquo;effarouchement et la gestion de la population.<\/p>\n<p>Les r\u00e9sultats g\u00e9n\u00e9r\u00e9s par ce projet marqueront une avanc\u00e9e significative dans l&rsquo;intersection de la technologie et de la gestion de la faune, tout en am\u00e9liorant la s\u00e9curit\u00e9 et la fiabilit\u00e9 des op\u00e9rations ferroviaires fran\u00e7aises.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-263 size-medium\" src=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife-300x186.jpg\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife-300x186.jpg 300w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife-1024x635.jpg 1024w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife-768x477.jpg 768w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife-1536x953.jpg 1536w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife-2048x1271.jpg 2048w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife-210x130.jpg 210w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig1-camera-traps-wildlife-1960x1216.jpg 1960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Fig. 1:\u00a0<i>Les pi\u00e8ges photographiques sont un outil \u00e9prouv\u00e9 pour suivre l&rsquo;abondance de la faune.<\/i><\/em><\/p>\n<p><a href=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-266 size-medium\" src=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings-300x178.jpg\" alt=\"\" width=\"300\" height=\"178\" srcset=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings-300x178.jpg 300w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings-1024x607.jpg 1024w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings-768x456.jpg 768w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings-1536x911.jpg 1536w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings-2048x1215.jpg 2048w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings-210x125.jpg 210w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig2-sediment-mud-markings-1960x1163.jpg 1960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Fig. 2: <i>Les s\u00e9diments boueux comme indicateurs de passage \u00e0 faune.<\/i><\/em><\/p>\n<p><a href=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig3-UAV-Drones.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-269 size-medium\" src=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig3-UAV-Drones-300x251.jpg\" alt=\"\" width=\"300\" height=\"251\" srcset=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig3-UAV-Drones-300x251.jpg 300w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig3-UAV-Drones-1024x856.jpg 1024w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig3-UAV-Drones-768x642.jpg 768w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig3-UAV-Drones-1536x1284.jpg 1536w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig3-UAV-Drones-210x175.jpg 210w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig3-UAV-Drones.jpg 1813w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Fig. 3: <i>Les enqu\u00eates par drone permettent de collecter des mod\u00e8les de terrain dans les zones sensibles et d&rsquo;observer directement la faune \u00e0 l&rsquo;aide de cam\u00e9ras thermiques.<\/i><\/em><\/p>\n<p><a href=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-272\" src=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-300x151.jpg\" alt=\"\" width=\"300\" height=\"151\" srcset=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-300x151.jpg 300w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-1024x517.jpg 1024w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-768x388.jpg 768w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-1536x776.jpg 1536w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-2048x1034.jpg 2048w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-210x106.jpg 210w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig4-mobile-mapping-imajnet-1960x990.jpg 1960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Fig. 4:\u00a0<i>Les images Mobile Mapping (<\/i><i>Imajnet<\/i><i>) peuvent \u00eatre utilis\u00e9es pour identifier les passages \u00e0 faune particuli\u00e8rement fr\u00e9quent\u00e9s par la coloration du gravier<\/i><\/em><\/p>\n<p><a href=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-275 size-medium\" src=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral-300x186.jpg\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral-300x186.jpg 300w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral-1024x636.jpg 1024w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral-768x477.jpg 768w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral-1536x954.jpg 1536w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral-2048x1272.jpg 2048w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral-210x130.jpg 210w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig5-sentinel2-bretagne-multispectral-1960x1217.jpg 1960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Fig. 5:\u00a0<i>Les donn\u00e9es multispectrales haute r\u00e9solution librement disponibles du programme de satellites Sentinel-2 de l&rsquo;ESA fournissent tous les six jours l&rsquo;occasion de calculer un mod\u00e8le de paysage classifiable pour l&rsquo;ensemble de la France.<\/i><\/em><\/p>\n<p><a href=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig6-schematic-model-french-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-278\" src=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig6-schematic-model-french-1024x468.jpg\" alt=\"\" width=\"980\" height=\"448\" srcset=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig6-schematic-model-french-1024x468.jpg 1024w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig6-schematic-model-french-300x137.jpg 300w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig6-schematic-model-french-768x351.jpg 768w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig6-schematic-model-french-1536x703.jpg 1536w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig6-schematic-model-french-210x96.jpg 210w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig6-schematic-model-french-1960x897.jpg 1960w\" sizes=\"auto, (max-width: 980px) 100vw, 980px\" \/><\/a><\/p>\n<p><em>Fig. 6: <i>Sch\u00e9ma<\/i><i> du prototype <\/i><i>d&rsquo;IA<\/i><i> multimodale (<\/i><i>Statut de la version : Juin 2023)<\/i><br \/>\n<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Methode<\/h2>\n<p>Notre syst\u00e8me accepte les donn\u00e9es spatio-temporelles pour g\u00e9n\u00e9rer des pr\u00e9visions de risques sur plusieurs horizons temporels (Fig. 6). Sa <b>robustesse<\/b> et son <b>niveau d&rsquo;automatisation <\/b>\u00e9lev\u00e9 permettent la production d&rsquo;un prototype pour <b>identifier les points d&rsquo;incidents critiques<\/b>. Des \u00e9tapes cl\u00e9s incluent la compilation de donn\u00e9es, le pr\u00e9traitement, la s\u00e9lection de syst\u00e8mes de classification et l&rsquo;\u00e9valuation des approches algorithmiques, avec une attention particuli\u00e8re \u00e0 <b>la facilit\u00e9 d&rsquo;utilisation et la scalabilit\u00e9.<\/b><\/p>\n<p>Pour pr\u00e9dire les niveaux de risque associ\u00e9s aux accidents de la faune sur le r\u00e9seau ferroviaire, nous <b>couplons <\/b>les classifications automatis\u00e9es de l&rsquo;<b>imagerie <\/b>terrestre (Fig. 4) et de la t\u00e9l\u00e9d\u00e9tection<br \/>\n(Fig. 5) <b>avec des mod\u00e8les de Machine Learning<\/b>. En pr\u00e9sence d&rsquo;une variance fluctuante, les mod\u00e8les de <b>r\u00e9seaux neuronaux <\/b><b>convolutionnels<\/b> &#8211; par exemple les nouvelles architectures avec m\u00e9moire \u00e0 court terme (CNN-LSTM) &#8211; sont plus performants que les mod\u00e8les de r\u00e9gression traditionnels.<\/p>\n<p>Nous \u00e9tudierons les <b>approches de fusion <\/b>pr\u00e9coce, tardive et hybride pour identifier le mod\u00e8le de pr\u00e9diction des risques le plus efficace. La fusion pr\u00e9coce simplifie le processus de formation en utilisant un seul mod\u00e8le, mais les r\u00e9sultats peuvent manquer d&rsquo;interpr\u00e9tabilit\u00e9. La fusion tardive fournit des d\u00e9cisions sp\u00e9cifiques \u00e0 la modalit\u00e9 et g\u00e8re bien les donn\u00e9es manquantes, mais n\u00e9cessite une ing\u00e9nierie des caract\u00e9ristiques \u00e9tendue et des mod\u00e8les multiples. La fusion hybride combine la fusion pr\u00e9coce et la fusion tardive, offrant des r\u00e9sultats complets au prix d&rsquo;une complexit\u00e9 accrue.<\/p>\n<p>Une <b>expertise du r\u00e9seau<\/b> ferroviaire et des habitats animaux locaux\u00a0 (Fig. 7) est essentielle pour <b>valider la pr\u00e9cision des r\u00e9sultats <\/b>pr\u00e9dictifs et la pertinence des donn\u00e9es d&rsquo;entr\u00e9e de r\u00e9f\u00e9rence. Nous utilisons des marques de boue sur les voies ferr\u00e9es (Fig. 2) comme indices indirects de la travers\u00e9e par les sangliers, valid\u00e9es par des pi\u00e8ges photographiques (Fig. 1). Les drones \u00e9quip\u00e9s d&rsquo;imagerie thermique infrarouge et de cam\u00e9ras zoom (Fig. 3) servent \u00e0 surveiller le comportement et la population de la faune sauvage, soit en comptant les animaux en vol, soit en analysant les images avec des r\u00e9seaux neuronaux de vision par ordinateur.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig7-hotspots-arima-prediction.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-281 size-medium_large\" src=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig7-hotspots-arima-prediction-768x746.jpg\" alt=\"\" width=\"768\" height=\"746\" srcset=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig7-hotspots-arima-prediction-768x746.jpg 768w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig7-hotspots-arima-prediction-300x291.jpg 300w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig7-hotspots-arima-prediction-1024x994.jpg 1024w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig7-hotspots-arima-prediction-1536x1492.jpg 1536w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig7-hotspots-arima-prediction-210x204.jpg 210w, https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/fig7-hotspots-arima-prediction.jpg 1666w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/p>\n<p><i>Fig. 7: <\/i><i>Carte thermique de pronostic pr\u00e9coce pour l&rsquo;\u00e9volution de l&rsquo;intensit\u00e9 des incidents pr\u00e9vue pour 2024. Moyenne mobile int\u00e9gr\u00e9e autor\u00e9gressive (ARIMA) bas\u00e9e sur les donn\u00e9es d&rsquo;incidents de 2015-2023 r\u00e9\u00e9chantillonn\u00e9es \u00e0 une r\u00e9solution de 20x20km.<br \/>\n<\/i><\/p>\n<p><i>Code couleur :<br \/>\nBleu &#8211; Moins d&rsquo;incidents pr\u00e9vus ; Blanc &#8211; Pas de changement \/ Pas de donn\u00e9es ; Jaune &#8211; Plus d&rsquo;incidents pr\u00e9vus ; Rouge &#8211; Forte intensification pr\u00e9vue.<\/i><\/p>\n<h2>Resultats<\/h2>\n<p>Le projet permettra d&rsquo;\u00e9tablir des <b>pr\u00e9visions robustes, pr\u00e9cises et opportunes des risques d&rsquo;accidents<\/b> impliquant des animaux sauvages (en particulier des sangliers) sur le r\u00e9seau ferroviaire fran\u00e7ais. Ces informations, d\u00e9riv\u00e9es de mod\u00e8les sophistiqu\u00e9s d&rsquo;apprentissage automatique et de la fusion de donn\u00e9es multimodales, permettront \u00e0 la SNCF de mieux comprendre les points n\u00e9vralgiques des incidents. Cela pourrait permettre de r\u00e9aliser d&rsquo;importantes \u00e9conomies en r\u00e9duisant le <b>nombre et la gravit\u00e9 des incidents<\/b> li\u00e9s \u00e0 la faune, ainsi que d&rsquo;am\u00e9liorer l&rsquo;<b>efficacit\u00e9 op\u00e9rationnelle<\/b>.<\/p>\n<p>En facilitant une prise de d\u00e9cision plus \u00e9clair\u00e9e, le syst\u00e8me aidera la SNCF \u00e0 mieux allouer les ressources pour les projets de construction d&rsquo;infrastructures, tels que les cl\u00f4tures et les passages pour animaux sauvages. En outre, l&rsquo;<b>atlas des pr\u00e9dictions <\/b>du mod\u00e8le peut servir d&rsquo;intrant essentiel pour les strat\u00e9gies de gestion de la faune, aidant ainsi la SNCF \u00e0 maintenir une relation harmonieuse avec le milieu environnant.<\/p>\n<p>\u00c0 l&rsquo;avenir, ce projet pourrait servir de mod\u00e8le pour de nouvelles esp\u00e8ces cibles ou d&rsquo;autres d\u00e9fis environnementaux fr\u00e9quemment rencontr\u00e9s. Au fur et \u00e0 mesure que le syst\u00e8me m\u00fbrit et que davantage de donn\u00e9es sont collect\u00e9es, il <b>apprendra continuellement <\/b>et <b>affinera ses pr\u00e9dictions<\/b>, ce qui augmentera encore sa valeur pour la SNCF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9sum\u00e9 L&rsquo;objectif du projet de recherche, qui est men\u00e9 \u00e0 la FHNW en collaboration avec SNCF R\u00e9seau, est d&rsquo;utiliser l&rsquo;intelligence artificielle (IA) et une int\u00e9gration de donn\u00e9es multimodales (s\u00e9ries temporelles multispectrales par satellite, images a\u00e9riennes, informations agricoles et climatologiques, ainsi que des donn\u00e9es provenantes de capteurs terrestres) pour mod\u00e9liser les probabilit\u00e9s de r\u00e9sidence de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-287","post","type-post","status-publish","format-standard","hentry","category-projet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l&#039;IA pour le SNCF R\u00e9seau - D\u00e9tection IA d\u2019animaux \u00e0 l&#039;aide des UAV<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l&#039;IA pour le SNCF R\u00e9seau - D\u00e9tection IA d\u2019animaux \u00e0 l&#039;aide des UAV\" \/>\n<meta property=\"og:description\" content=\"R\u00e9sum\u00e9 L&rsquo;objectif du projet de recherche, qui est men\u00e9 \u00e0 la FHNW en collaboration avec SNCF R\u00e9seau, est d&rsquo;utiliser l&rsquo;intelligence artificielle (IA) et une int\u00e9gration de donn\u00e9es multimodales (s\u00e9ries temporelles multispectrales par satellite, images a\u00e9riennes, informations agricoles et climatologiques, ainsi que des donn\u00e9es provenantes de capteurs terrestres) pour mod\u00e9liser les probabilit\u00e9s de r\u00e9sidence de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/\" \/>\n<meta property=\"og:site_name\" content=\"D\u00e9tection IA d\u2019animaux \u00e0 l&#039;aide des UAV\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-19T09:03:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T12:58:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg\" \/>\n<meta name=\"author\" content=\"Adrian Meyer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrian Meyer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/\"},\"author\":{\"name\":\"Adrian Meyer\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#\\\/schema\\\/person\\\/4d9c08addcb8ae627f031bb85e69f668\"},\"headline\":\"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l&rsquo;IA pour le SNCF R\u00e9seau\",\"datePublished\":\"2023-06-19T09:03:55+00:00\",\"dateModified\":\"2023-09-14T12:58:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/\"},\"wordCount\":1676,\"publisher\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wilddrone.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg\",\"articleSection\":[\"Projet de recherche\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/\",\"url\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/\",\"name\":\"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l'IA pour le SNCF R\u00e9seau - D\u00e9tection IA d\u2019animaux \u00e0 l'aide des UAV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wilddrone.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg\",\"datePublished\":\"2023-06-19T09:03:55+00:00\",\"dateModified\":\"2023-09-14T12:58:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wilddrone.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/wilddrone.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/detection-faune-ia-sncf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l&#8217;IA pour le SNCF R\u00e9seau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/\",\"name\":\"Wildtier-Monitoring mit UAVs\",\"description\":\"Projet FHNW: T\u00e9l\u00e9d\u00e9tection IA de la Faune Sauvage\",\"publisher\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#organization\",\"name\":\"Adrian Meyer - Institut Geomatik FHNW\",\"url\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wilddrone.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/xqN4uf35_400x4001.jpg\",\"contentUrl\":\"https:\\\/\\\/wilddrone.ch\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/xqN4uf35_400x4001.jpg\",\"width\":400,\"height\":400,\"caption\":\"Adrian Meyer - Institut Geomatik FHNW\"},\"image\":{\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wilddrone.ch\\\/fr\\\/#\\\/schema\\\/person\\\/4d9c08addcb8ae627f031bb85e69f668\",\"name\":\"Adrian Meyer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03f4bfdc91941b9ccb5a73472d775774c254ee32b9daf4effe519474952fb9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03f4bfdc91941b9ccb5a73472d775774c254ee32b9daf4effe519474952fb9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/03f4bfdc91941b9ccb5a73472d775774c254ee32b9daf4effe519474952fb9ed?s=96&d=mm&r=g\",\"caption\":\"Adrian Meyer\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l'IA pour le SNCF R\u00e9seau - D\u00e9tection IA d\u2019animaux \u00e0 l'aide des UAV","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l'IA pour le SNCF R\u00e9seau - D\u00e9tection IA d\u2019animaux \u00e0 l'aide des UAV","og_description":"R\u00e9sum\u00e9 L&rsquo;objectif du projet de recherche, qui est men\u00e9 \u00e0 la FHNW en collaboration avec SNCF R\u00e9seau, est d&rsquo;utiliser l&rsquo;intelligence artificielle (IA) et une int\u00e9gration de donn\u00e9es multimodales (s\u00e9ries temporelles multispectrales par satellite, images a\u00e9riennes, informations agricoles et climatologiques, ainsi que des donn\u00e9es provenantes de capteurs terrestres) pour mod\u00e9liser les probabilit\u00e9s de r\u00e9sidence de la [&hellip;]","og_url":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/","og_site_name":"D\u00e9tection IA d\u2019animaux \u00e0 l'aide des UAV","article_published_time":"2023-06-19T09:03:55+00:00","article_modified_time":"2023-09-14T12:58:54+00:00","og_image":[{"url":"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg","type":"","width":"","height":""}],"author":"Adrian Meyer","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Adrian Meyer","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/#article","isPartOf":{"@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/"},"author":{"name":"Adrian Meyer","@id":"https:\/\/wilddrone.ch\/fr\/#\/schema\/person\/4d9c08addcb8ae627f031bb85e69f668"},"headline":"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l&rsquo;IA pour le SNCF R\u00e9seau","datePublished":"2023-06-19T09:03:55+00:00","dateModified":"2023-09-14T12:58:54+00:00","mainEntityOfPage":{"@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/"},"wordCount":1676,"publisher":{"@id":"https:\/\/wilddrone.ch\/fr\/#organization"},"image":{"@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/#primaryimage"},"thumbnailUrl":"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg","articleSection":["Projet de recherche"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/","url":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/","name":"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l'IA pour le SNCF R\u00e9seau - D\u00e9tection IA d\u2019animaux \u00e0 l'aide des UAV","isPartOf":{"@id":"https:\/\/wilddrone.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/#primaryimage"},"image":{"@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/#primaryimage"},"thumbnailUrl":"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg","datePublished":"2023-06-19T09:03:55+00:00","dateModified":"2023-09-14T12:58:54+00:00","breadcrumb":{"@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/#primaryimage","url":"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg","contentUrl":"https:\/\/wilddrone.ch\/wp-content\/uploads\/2023\/06\/header-adrian-meyer-fhnw-sncf-wildlife-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/wilddrone.ch\/fr\/detection-faune-ia-sncf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wilddrone.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9tection pr\u00e9dictive de la faune bas\u00e9e sur l&#8217;IA pour le SNCF R\u00e9seau"}]},{"@type":"WebSite","@id":"https:\/\/wilddrone.ch\/fr\/#website","url":"https:\/\/wilddrone.ch\/fr\/","name":"Wildtier-Monitoring mit UAVs","description":"Projet FHNW: T\u00e9l\u00e9d\u00e9tection IA de la Faune Sauvage","publisher":{"@id":"https:\/\/wilddrone.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wilddrone.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wilddrone.ch\/fr\/#organization","name":"Adrian Meyer - Institut Geomatik FHNW","url":"https:\/\/wilddrone.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wilddrone.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/wilddrone.ch\/wp-content\/uploads\/2019\/06\/xqN4uf35_400x4001.jpg","contentUrl":"https:\/\/wilddrone.ch\/wp-content\/uploads\/2019\/06\/xqN4uf35_400x4001.jpg","width":400,"height":400,"caption":"Adrian Meyer - Institut Geomatik FHNW"},"image":{"@id":"https:\/\/wilddrone.ch\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/wilddrone.ch\/fr\/#\/schema\/person\/4d9c08addcb8ae627f031bb85e69f668","name":"Adrian Meyer","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/03f4bfdc91941b9ccb5a73472d775774c254ee32b9daf4effe519474952fb9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/03f4bfdc91941b9ccb5a73472d775774c254ee32b9daf4effe519474952fb9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/03f4bfdc91941b9ccb5a73472d775774c254ee32b9daf4effe519474952fb9ed?s=96&d=mm&r=g","caption":"Adrian Meyer"}}]}},"_links":{"self":[{"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/posts\/287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/comments?post=287"}],"version-history":[{"count":9,"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/posts\/287\/revisions"}],"predecessor-version":[{"id":338,"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/posts\/287\/revisions\/338"}],"wp:attachment":[{"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/media?parent=287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/categories?post=287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wilddrone.ch\/fr\/wp-json\/wp\/v2\/tags?post=287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}